{"id":498,"date":"2023-09-19T08:47:15","date_gmt":"2023-09-19T08:47:15","guid":{"rendered":"https:\/\/sinotechluton.com\/?page_id=498"},"modified":"2024-08-29T10:40:35","modified_gmt":"2024-08-29T10:40:35","slug":"privacy-policy","status":"publish","type":"page","link":"https:\/\/sinotechluton.com\/de\/privacy-policy\/","title":{"rendered":"Datenschutzrichtlinie\u00a0"},"content":{"rendered":"<div class=\"gb-container gb-container-5484461f\">\n<div class=\"gb-container gb-container-472213b1\">\n\n<h2 class=\"gb-headline gb-headline-649b29b2 gb-headline-text\">Wer wir sind<\/h2>\n\n\n\n<p class=\"gb-headline gb-headline-a205e938 gb-headline-text\">Unsere Website-Adresse lautet: https:\/\/sinotechluton.com\/<\/p>\n\n\n\n<h2 class=\"gb-headline gb-headline-cdeb2041 gb-headline-text\">Kommentare<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Besucher Kommentare auf der Website hinterlassen, erheben wir die in dem Kommentarformular angezeigten Daten sowie au\u00dferdem die IP-Adresse des Besuchers und die Browser-User-Agent-Zeichenkette, um Spam-Erkennung zu unterst\u00fctzen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine anonymisierte Zeichenkette, die aus Ihrer E-Mail-Adresse erstellt wurde (auch \u201eHash\u201c genannt), kann dem Gravatar-Dienst zur Verf\u00fcgung gestellt werden, um zu pr\u00fcfen, ob Sie diesen nutzen. Nach Genehmigung Ihres Kommentars ist Ihr Profilbild im Zusammenhang mit Ihrem Kommentar \u00f6ffentlich sichtbar.<\/p>\n\n\n\n<h2 class=\"gb-headline gb-headline-6be34f95 gb-headline-text\">Medien<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie Bilder auf die Website hochladen, sollten Sie darauf verzichten, Bilder mit eingebetteten Standortdaten (EXIF-GPS) hochzuladen. Besucher der Website k\u00f6nnen Standortdaten aus den auf der Website ver\u00f6ffentlichten Bildern herunterladen und extrahieren.<\/p>\n\n\n\n<h2 class=\"gb-headline gb-headline-60b9cab7 gb-headline-text\">Cookies<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie einen Kommentar auf unserer Website abgeben, k\u00f6nnen Sie sich daf\u00fcr entscheiden, Ihren Namen, Ihre E-Mail-Adresse und Ihre Website in Cookies speichern zu lassen. Diese dienen Ihrer Bequemlichkeit, damit Sie Ihre Angaben nicht erneut eingeben m\u00fcssen, wenn Sie einen weiteren Kommentar abgeben. Diese Cookies bleiben ein Jahr lang gespeichert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie unsere Anmeldeseite besuchen, setzen wir ein tempor\u00e4res Cookie, um festzustellen, ob Ihr Browser Cookies akzeptiert. Dieses Cookie enth\u00e4lt keine personenbezogenen Daten und wird gel\u00f6scht, sobald Sie Ihren Browser schlie\u00dfen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bei der Anmeldung richten wir zudem mehrere Cookies ein, um Ihre Anmeldeinformationen und Ihre Bildschirmanzeige-Einstellungen zu speichern. Anmelde-Cookies bleiben zwei Tage lang g\u00fcltig, Cookies f\u00fcr Bildschirmeinstellungen ein Jahr lang. Wenn Sie \u201cAngemeldet bleiben\u201d ausw\u00e4hlen, bleibt Ihre Anmeldung zwei Wochen lang aktiv. Wenn Sie sich von Ihrem Konto abmelden, werden die Anmelde-Cookies entfernt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie einen Artikel bearbeiten oder ver\u00f6ffentlichen, wird zus\u00e4tzlich ein Cookie in Ihrem Browser gespeichert. Dieses Cookie enth\u00e4lt keine personenbezogenen Daten und zeigt lediglich die ID des Artikels an, den Sie gerade bearbeitet haben. Es l\u00e4uft nach einem Tag ab.<\/p>\n\n\n\n<h2 class=\"gb-headline gb-headline-3d1f6194 gb-headline-text\">Einbettende Inhalte von anderen Websites<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Artikel auf dieser Website k\u00f6nnen eingebettete Inhalte (z.\u202fB. Videos, Bilder, Artikel usw.) enthalten. Eingebettete Inhalte von anderen Websites verhalten sich genau so, als h\u00e4tte der Besucher diese andere Website besucht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diese Websites k\u00f6nnen Daten \u00fcber Sie erheben, Cookies verwenden, zus\u00e4tzliche Tracking-Dienste Dritter einbetten und Ihre Interaktion mit diesem eingebetteten Inhalt \u00fcberwachen \u2013 einschlie\u00dflich der Verfolgung Ihrer Interaktion mit dem eingebetteten Inhalt, falls Sie \u00fcber ein Konto verf\u00fcgen und bei dieser Website angemeldet sind.<\/p>\n\n\n\n<h2 class=\"gb-headline gb-headline-854c0837 gb-headline-text\">Mit wem wir Ihre Daten teilen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie eine Passwortzur\u00fccksetzung anfordern, wird Ihre IP-Adresse in die R\u00fccksetz-E-Mail aufgenommen.<\/p>\n\n\n\n<h2 class=\"gb-headline gb-headline-7ed684dc gb-headline-text\">Wie lange wir Ihre Daten speichern<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie einen Kommentar abgeben, werden der Kommentar und seine Metadaten unbefristet gespeichert. Dadurch k\u00f6nnen wir etwaige Folgekommentare automatisch erkennen und freigeben, statt sie in einer Moderationswarteschlange zu halten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr Nutzer, die sich auf unserer Website registrieren (sofern vorhanden), speichern wir zudem die von ihnen in ihrem Benutzerprofil angegebenen pers\u00f6nlichen Informationen. Alle Nutzer k\u00f6nnen ihre pers\u00f6nlichen Informationen jederzeit einsehen, bearbeiten oder l\u00f6schen (au\u00dfer ihren Benutzernamen \u00e4ndern). Website-Administratoren k\u00f6nnen diese Informationen ebenfalls einsehen und bearbeiten.<\/p>\n\n\n\n<h2 class=\"gb-headline gb-headline-2f7d2a55 gb-headline-text\">Welche Rechte Sie bez\u00fcglich Ihrer Daten haben<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie \u00fcber ein Konto auf dieser Website verf\u00fcgen oder Kommentare abgegeben haben, k\u00f6nnen Sie beantragen, eine Exportdatei der personenbezogenen Daten zu erhalten, die wir \u00fcber Sie gespeichert haben \u2013 einschlie\u00dflich aller Daten, die Sie uns zur Verf\u00fcgung gestellt haben. Sie k\u00f6nnen zudem beantragen, dass wir alle personenbezogenen Daten, die wir \u00fcber Sie gespeichert haben, l\u00f6schen. Davon ausgenommen sind Daten, die wir aus administrativen, rechtlichen oder Sicherheitsgr\u00fcnden aufbewahren m\u00fcssen.<\/p>\n\n\n\n<h2 class=\"gb-headline gb-headline-398f42e4 gb-headline-text\">Wohin wir Ihre Daten senden<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Besucher-Kommentare k\u00f6nnen mithilfe eines automatisierten Spam-Erkennungsdienstes \u00fcberpr\u00fcft werden.<\/p>\n\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Who we are Our website address is: https:\/\/sinotechluton.com\/ Comments When visitors leave comments on the site we collect the data shown in the comments form, and also the visitor\u2019s IP address and browser user agent string to help spam detection. An anonymized string created from your email address (also called a hash) may be provided &#8230; <a title=\"Datenschutzrichtlinie\u00a0\" class=\"read-more\" href=\"https:\/\/sinotechluton.com\/de\/privacy-policy\/\" aria-label=\"Mehr Informationen \u00fcber Privacy Policy\u00a0\">Weiterlesen &#8230;<\/a><\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-498","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Privacy Policy\u00a0 - SinoTech Luton<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sinotechluton.com\/de\/privacy-policy\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy Policy\u00a0 - SinoTech Luton\" \/>\n<meta property=\"og:description\" content=\"Who we are Our website address is: https:\/\/sinotechluton.com\/ Comments When visitors leave comments on the site we collect the data shown in the comments form, and also the visitor\u2019s IP address and browser user agent string to help spam detection. An anonymized string created from your email address (also called a hash) may be provided ... Weiterlesen ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sinotechluton.com\/de\/privacy-policy\/\" \/>\n<meta property=\"og:site_name\" content=\"SinoTech Luton\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-29T10:40:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sinotechluton.com\\\/privacy-policy\\\/\",\"url\":\"https:\\\/\\\/sinotechluton.com\\\/privacy-policy\\\/\",\"name\":\"Privacy Policy\u00a0 - SinoTech Luton\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sinotechluton.com\\\/#website\"},\"datePublished\":\"2023-09-19T08:47:15+00:00\",\"dateModified\":\"2024-08-29T10:40:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sinotechluton.com\\\/privacy-policy\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sinotechluton.com\\\/privacy-policy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sinotechluton.com\\\/privacy-policy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sinotechluton.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy Policy\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sinotechluton.com\\\/#website\",\"url\":\"https:\\\/\\\/sinotechluton.com\\\/\",\"name\":\"SinoTech Luton\",\"description\":\"Leading Manufacturer of All Sorts of Construction Machinery\",\"publisher\":{\"@id\":\"https:\\\/\\\/sinotechluton.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sinotechluton.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sinotechluton.com\\\/#organization\",\"name\":\"SinoTech Luton\",\"url\":\"https:\\\/\\\/sinotechluton.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/sinotechluton.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sinotechluton.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/1.png\",\"contentUrl\":\"https:\\\/\\\/sinotechluton.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/1.png\",\"width\":2029,\"height\":516,\"caption\":\"SinoTech Luton\"},\"image\":{\"@id\":\"https:\\\/\\\/sinotechluton.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutzrichtlinie\u00a0 - SinoTech Luton","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sinotechluton.com\/de\/privacy-policy\/","og_locale":"de_DE","og_type":"article","og_title":"Privacy Policy\u00a0 - SinoTech Luton","og_description":"Who we are Our website address is: https:\/\/sinotechluton.com\/ Comments When visitors leave comments on the site we collect the data shown in the comments form, and also the visitor\u2019s IP address and browser user agent string to help spam detection. An anonymized string created from your email address (also called a hash) may be provided ... Weiterlesen ...","og_url":"https:\/\/sinotechluton.com\/de\/privacy-policy\/","og_site_name":"SinoTech Luton","article_modified_time":"2024-08-29T10:40:35+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sinotechluton.com\/privacy-policy\/","url":"https:\/\/sinotechluton.com\/privacy-policy\/","name":"Datenschutzrichtlinie\u00a0 - SinoTech Luton","isPartOf":{"@id":"https:\/\/sinotechluton.com\/#website"},"datePublished":"2023-09-19T08:47:15+00:00","dateModified":"2024-08-29T10:40:35+00:00","breadcrumb":{"@id":"https:\/\/sinotechluton.com\/privacy-policy\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sinotechluton.com\/privacy-policy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sinotechluton.com\/privacy-policy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sinotechluton.com\/"},{"@type":"ListItem","position":2,"name":"Privacy Policy\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/sinotechluton.com\/#website","url":"https:\/\/sinotechluton.com\/","name":"SinoTech Luton","description":"F\u00fchrender Hersteller aller Arten von Baumaschinen","publisher":{"@id":"https:\/\/sinotechluton.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sinotechluton.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/sinotechluton.com\/#organization","name":"SinoTech Luton","url":"https:\/\/sinotechluton.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/sinotechluton.com\/#\/schema\/logo\/image\/","url":"https:\/\/sinotechluton.com\/wp-content\/uploads\/2024\/03\/1.png","contentUrl":"https:\/\/sinotechluton.com\/wp-content\/uploads\/2024\/03\/1.png","width":2029,"height":516,"caption":"SinoTech Luton"},"image":{"@id":"https:\/\/sinotechluton.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/sinotechluton.com\/de\/wp-json\/wp\/v2\/pages\/498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinotechluton.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sinotechluton.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sinotechluton.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sinotechluton.com\/de\/wp-json\/wp\/v2\/comments?post=498"}],"version-history":[{"count":5,"href":"https:\/\/sinotechluton.com\/de\/wp-json\/wp\/v2\/pages\/498\/revisions"}],"predecessor-version":[{"id":3803,"href":"https:\/\/sinotechluton.com\/de\/wp-json\/wp\/v2\/pages\/498\/revisions\/3803"}],"wp:attachment":[{"href":"https:\/\/sinotechluton.com\/de\/wp-json\/wp\/v2\/media?parent=498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}